{"id":461,"date":"2024-02-05T13:19:12","date_gmt":"2024-02-05T16:19:12","guid":{"rendered":"https:\/\/thiagostolte.com.br\/oguiacompletodeleilaodeimoveis\/?page_id=461"},"modified":"2024-02-05T13:44:24","modified_gmt":"2024-02-05T16:44:24","slug":"elementor-461","status":"publish","type":"page","link":"https:\/\/thiagostolte.com.br\/oguiacompletodeleilaodeimoveis\/elementor-461\/","title":{"rendered":"Termos de Uso"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"461\" class=\"elementor elementor-461\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71b9cc7 e-flex e-con-boxed e-con e-parent\" data-id=\"71b9cc7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-256c217 elementor-widget elementor-widget-text-editor\" data-id=\"256c217\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #333333;\">Termos e Condi\u00e7\u00f5es de Uso<\/span><\/h4><p><span style=\"color: #333333;\">Seja bem-vindo ao O Guia Completo de Leil\u00f5es de Im\u00f3veis!<\/span><\/p><p><span style=\"color: #333333;\">Estes termos e condi\u00e7\u00f5es descrevem as regras de uso do site da empresa Guia Completo de Leil\u00f5es de Im\u00f3veis, localizado no endere\u00e7o https:\/\/oguiacompletodeleilaodeimoveis.thiagostolte.com.br\/.<\/span><\/p><p><span style=\"color: #333333;\">Ao acessar este site, consideramos que voc\u00ea est\u00e1 de acordo com os termos e condi\u00e7\u00f5es abaixo. N\u00e3o continue a usar o O Guia Completo de Leil\u00f5es de Im\u00f3veis caso voc\u00ea discorde dos termos e condi\u00e7\u00f5es descritos neste contrato.<\/span><\/p><h4><span style=\"color: #333333;\">Cookies:<\/span><\/h4><p><span style=\"color: #333333;\">O site usa cookies para ajudar na personaliza\u00e7\u00e3o da sua experi\u00eancia na internet. Ao acessar o site O Guia Completo de Leil\u00f5es de Im\u00f3veis, voc\u00ea concorda com o uso dos cookies requeridos.<\/span><\/p><p><span style=\"color: #333333;\">Cookies s\u00e3o arquivos de texto inseridos no seu disco r\u00edgido por um servidor de p\u00e1gina web. Os cookies n\u00e3o t\u00eam permiss\u00e3o para executar programas ou transferir v\u00edrus para seu computador. Os cookies s\u00e3o associados exclusivamente a voc\u00ea e s\u00f3 podem ser lidos pelo servidor web do dom\u00ednio que emitiu o cookie.<\/span><\/p><p><span style=\"color: #333333;\">N\u00f3s podemos usar cookies para coletar, armazenar ou rastrear informa\u00e7\u00f5es para finalidades estat\u00edsticas e mercadol\u00f3gicas do nosso site. Voc\u00ea tem a op\u00e7\u00e3o de aceitar ou rejeitar os cookies opcionais. Existem alguns cookies obrigat\u00f3rios, que s\u00e3o necess\u00e1rios para o funcionamento de nosso site. Esses cookies obrigat\u00f3rios s\u00e3o requerem seu consentimento. Por favor, tenha em mente que, ao aceitar os cookies obrigat\u00f3rios, voc\u00ea tamb\u00e9m estar\u00e1 aceitando cookies de terceiros, que podem ser usados por terceiros caso voc\u00ea utilize servi\u00e7os fornecidos por eles em nosso site \u2013 por exemplo, uma janela de reprodu\u00e7\u00e3o de v\u00eddeo fornecida por empresas terceiras e integrada ao nosso site.<\/span><\/p><h4><span style=\"color: #333333;\">Licen\u00e7a:<\/span><\/h4><p><span style=\"color: #333333;\">Exceto em casos em que for indicado o contr\u00e1rio, Guia Completo de Leil\u00f5es de Im\u00f3veis e seus licenciados t\u00eam direito \u00e0 propriedade intelectual de todo o material postado no O Guia Completo de Leil\u00f5es de Im\u00f3veis. Todos os direitos \u00e0 propriedade intelectual s\u00e3o reservados.<\/span><\/p><p><span style=\"color: #333333;\">Voc\u00ea n\u00e3o tem permiss\u00e3o para:<\/span><\/p><ul><li><span style=\"color: #333333;\">Copiar ou republicar materiais do O Guia Completo de Leil\u00f5es de Im\u00f3veis<\/span><\/li><li><span style=\"color: #333333;\">Vender, alugar ou sublocar materiais do O Guia Completo de Leil\u00f5es de Im\u00f3veis<\/span><\/li><li><span style=\"color: #333333;\">Reproduzir, duplicar ou copiar materiais do O Guia Completo de Leil\u00f5es de Im\u00f3veis<\/span><\/li><li><span style=\"color: #333333;\">Redistribuir conte\u00fados do O Guia Completo de Leil\u00f5es de Im\u00f3veis<\/span><\/li><\/ul><p><span style=\"color: #333333;\">Este Acordo ter\u00e1 efeito a partir da data presente.<\/span><\/p><p><span style=\"color: #333333;\">Partes deste site oferecem ao usu\u00e1rio a oportunidade de postar e discutir opini\u00f5es e informa\u00e7\u00f5es em determinadas \u00e1reas. Guia Completo de Leil\u00f5es de Im\u00f3veis n\u00e3o filtra, edita, publica ou revisa Coment\u00e1rios antes que eles sejam apresentados no site. Coment\u00e1rios refletem as opini\u00f5es da pessoa que os posta. Na extens\u00e3o em que as leis aplic\u00e1veis permitem, Guia Completo de Leil\u00f5es de Im\u00f3veis n\u00e3o se responsabiliza legalmente pelos Coment\u00e1rios ou quaisquer danos, riscos ou despesas causadas ou sofridas como resultado do uso, e\/ou postagem e\/ou apar\u00eancia dos Coment\u00e1rios deste site.<\/span><\/p><p><span style=\"color: #333333;\">Guia Completo de Leil\u00f5es de Im\u00f3veis reserva para si o direito de remover quaisquer Coment\u00e1rios que possam ser considerados inapropriados, ofensivos ou quebrem os Termos e Condi\u00e7\u00f5es deste contrato.<\/span><\/p><p><span style=\"color: #333333;\">Voc\u00ea declara e garante que:<\/span><\/p><ul><li><span style=\"color: #333333;\">Voc\u00ea tem o direito de postar Coment\u00e1rios em nosso site e tem todas as licen\u00e7as e consentimentos para tal;<\/span><\/li><li><span style=\"color: #333333;\">Seus Coment\u00e1rios n\u00e3o invadem qualquer propriedade intelectual, incluindo direitos autorais, patentes ou marcas registradas de terceiros;<\/span><\/li><li><span style=\"color: #333333;\">Seus Coment\u00e1rios n\u00e3o cont\u00e9m material difamat\u00f3rio, injurioso, ofensivo, indecente ou de alguma forma il\u00edcito, que \u00e9 invas\u00e3o de privacidade.<\/span><\/li><li><span style=\"color: #333333;\">Seus Coment\u00e1rios n\u00e3o ser\u00e3o usados para solicitar ou promover neg\u00f3cios ou apresentar atividades comerciais ou atividades il\u00edcitas.<\/span><\/li><\/ul><p><span style=\"color: #333333;\">Voc\u00ea por meio deste concede a Guia Completo de Leil\u00f5es de Im\u00f3veis a licen\u00e7a n\u00e3o-exclusiva de usar, reproduzir, editar e autorizar outros a usar, reproduzir ou editar qualquer um de seus Coment\u00e1rios em qualquer e todas as formas, formatos e m\u00eddias.<\/span><\/p><h4><span style=\"color: #333333;\">Cria\u00e7\u00e3o de links para nosso conte\u00fado<\/span><\/h4><p><span style=\"color: #333333;\">As seguintes organiza\u00e7\u00f5es podem criar links para nosso Site sem a necessidade de aprova\u00e7\u00e3o pr\u00e9via por escrito:<\/span><\/p><ul><li><span style=\"color: #333333;\">Ag\u00eancias governamentais;<\/span><\/li><li><span style=\"color: #333333;\">Mecanismos de busca;<\/span><\/li><li><span style=\"color: #333333;\">Organiza\u00e7\u00f5es de m\u00eddia;<\/span><\/li><li><span style=\"color: #333333;\">Distribuidores de diret\u00f3rios online podem inserir links para nosso Site na mesma maneira que inserem hiperlinks para Sites de outras empresas listadas; e<\/span><\/li><li><span style=\"color: #333333;\">Empresas credenciadas, exceto organiza\u00e7\u00f5es angariantes sem fins lucrativos e grupos de arrecada\u00e7\u00e3o de fundos para institui\u00e7\u00f5es de caridade, que n\u00e3o podem inserir links para nosso Site sem aprova\u00e7\u00e3o pr\u00e9via.<\/span><\/li><\/ul><p><span style=\"color: #333333;\">Essas organiza\u00e7\u00f5es podem postar links para nossa p\u00e1gina inicial, nossas publica\u00e7\u00f5es ou outras informa\u00e7\u00f5es do Site, contanto que o link: (a) n\u00e3o seja, de forma alguma, enganoso; (b) n\u00e3o insinue falsamente a exist\u00eancia de uma rela\u00e7\u00e3o de patroc\u00ednio, endosso, ou aprova\u00e7\u00e3o nossa a produtos e\/ou servi\u00e7os; e (c) seja apropriado ao contexto em que est\u00e1 sendo inserido.<\/span><\/p><p><span style=\"color: #333333;\">N\u00f3s podemos considerar e aprovar solicita\u00e7\u00f5es de link feitas pelos seguintes tipos de organiza\u00e7\u00f5es:<\/span><\/p><ul><li><span style=\"color: #333333;\">fontes de informa\u00e7\u00e3o bem conhecidas sobre produtos e neg\u00f3cios;<\/span><\/li><li><span style=\"color: #333333;\">sites comunit\u00e1rios ponto.com;<\/span><\/li><li><span style=\"color: #333333;\">associa\u00e7\u00f5es e outros grupos que representem institui\u00e7\u00f5es de caridade;<\/span><\/li><li><span style=\"color: #333333;\">distribuidores de diret\u00f3rios online;<\/span><\/li><li><span style=\"color: #333333;\">portais de internet;<\/span><\/li><li><span style=\"color: #333333;\">firmas de contabilidade, advocacia e consultoria; e<\/span><\/li><li><span style=\"color: #333333;\">institui\u00e7\u00f5es educacionais e associa\u00e7\u00f5es de classe.<\/span><\/li><\/ul><p><span style=\"color: #333333;\">N\u00f3s vamos aprovar solicita\u00e7\u00f5es de link feitas pelos tipos de organiza\u00e7\u00e3o listados acima se julgarmos que: (a) o link n\u00e3o \u00e9 desfavor\u00e1vel para nossa imagem e\/ou para a imagem de empresas credenciadas; (b) a organiza\u00e7\u00e3o solicitante n\u00e3o possui hist\u00f3rico negativo conosco; (c) o benef\u00edcio que ganhamos com a visibilidade do link compensa a aus\u00eancia do Guia Completo de Leil\u00f5es de Im\u00f3veis; e (d) o link ser\u00e1 inserido em um contexto geral informativo.<\/span><\/p><p><span style=\"color: #333333;\">Essas organiza\u00e7\u00f5es podem postar links para nossa p\u00e1gina inicial contanto que o link: (a) n\u00e3o seja, de forma alguma, enganoso; (b) n\u00e3o insinue falsamente a exist\u00eancia de uma rela\u00e7\u00e3o de patroc\u00ednio, endosso, ou aprova\u00e7\u00e3o de produtos e\/ou servi\u00e7os da nossa parte; e (c) seja apropriado ao contexto em que est\u00e1 sendo inserido.<\/span><\/p><p><span style=\"color: #333333;\">Se voc\u00ea representa uma das organiza\u00e7\u00f5es listadas no par\u00e1grafo 2 acima e est\u00e1 interessado em postar um link para nosso site, voc\u00ea deve nos informar de seu interesse enviando um e-mail para Guia Completo de Leil\u00f5es de Im\u00f3veis. Por favor, inclua seu some, o nome da sua organiza\u00e7\u00e3o e suas informa\u00e7\u00f5es de contato, assim como a URL do seu site, uma lista das URLs do nosso site que voc\u00ea pretende usar como links, e uma lista dos sites nos quais voc\u00ea pretende publicar nossas URLs. Aguarde entre 2 e 3 semanas para receber uma resposta.<\/span><\/p><p><span style=\"color: #333333;\">Organiza\u00e7\u00f5es aprovadas poder\u00e3o publicar links para nosso Site das seguintes formas:<\/span><\/p><ul><li><span style=\"color: #333333;\">Usando nosso nome corporativo; ou<\/span><\/li><li><span style=\"color: #333333;\">Usando a URL para onde o link redireciona; ou<\/span><\/li><li><span style=\"color: #333333;\">Usando qualquer outra descri\u00e7\u00e3o do nosso Site que fa\u00e7a sentido dentro do contexto e do formato do conte\u00fado onde o link est\u00e1 sendo inserido.<\/span><\/li><\/ul><p><span style=\"color: #333333;\">N\u00e3o ser\u00e1 permitido o uso ou a publica\u00e7\u00e3o de links para o logo e\/ou outros elementos visuais da Guia Completo de Leil\u00f5es de Im\u00f3veis sem um acordo de licen\u00e7a para o uso da marca registrada.<\/span><\/p><h4><span style=\"color: #333333;\">Responsabiliza\u00e7\u00e3o pelo Conte\u00fado:<\/span><\/h4><p><span style=\"color: #333333;\">N\u00e3o seremos responsabilizados legalmente por qualquer conte\u00fado que apare\u00e7a no seu Site. Voc\u00ea concorda em nos proteger e nos defender contra todas as acusa\u00e7\u00f5es que forem levantadas no seu Site. Nenhum link deve aparecer em qualquer Site que possa ser interpretado como difamat\u00f3rio, obsceno, criminoso, ou que infrinja, viole ou defenda a viola\u00e7\u00e3o dos direitos de terceiros.<\/span><\/p><h4><span style=\"color: #333333;\">Reserva de Direitos:<\/span><\/h4><p><span style=\"color: #333333;\">Reservamos nosso direito de solicitar que voc\u00ea remova todos os links ou quaisquer links que redirecionem para nosso site. Voc\u00ea concorda em remover imediatamente todos os links para nosso site assim que a remo\u00e7\u00e3o for solicitada. Tamb\u00e9m reservamos nosso direito de corrigir e alterar estes termos e condi\u00e7\u00f5es a qualquer momento. Ao publicar continuadamente links para nosso site, voc\u00ea concorda a seguir estes termos e condi\u00e7\u00f5es sobre links.<\/span><\/p><h4><span style=\"color: #333333;\">Remo\u00e7\u00e3o de links postados em nosso site:<\/span><\/h4><p><span style=\"color: #333333;\">Se voc\u00ea encontrar qualquer link em nosso Site que seja de qualquer forma ofensivo, voc\u00ea tem a liberdade de entrar em contato conosco e nos informar do problema a qualquer momento. Vamos considerar as solicita\u00e7\u00f5es de remo\u00e7\u00e3o de links, mas n\u00e3o somos obrigados a remover quaisquer links do nosso site nem a responder diretamente \u00e0 sua solicita\u00e7\u00e3o.<\/span><\/p><p><span style=\"color: #333333;\">N\u00f3s n\u00e3o garantimos que as informa\u00e7\u00f5es continas neste site s\u00e3o corretas. N\u00f3s n\u00e3o garantimos integralidade ou exatid\u00e3o do conte\u00fado. N\u00e3o garantimos que o site se manter\u00e1 dispon\u00edvel ou que o material do site se manter\u00e1 atualizado.<\/span><\/p><h4><span style=\"color: #333333;\">Declara\u00e7\u00e3o de Isen\u00e7\u00e3o de Responsabilidade:<\/span><\/h4><p><span style=\"color: #333333;\">No m\u00e1ximo poss\u00edvel permitido por lei, n\u00f3s exclu\u00edmos todas as representa\u00e7\u00f5es, garantias e condi\u00e7\u00f5es relativas ao nosso site e ao uso deste site. Nada nesta declara\u00e7\u00e3o de isen\u00e7\u00e3o de responsabilidade vai:<\/span><\/p><ul><li><span style=\"color: #333333;\">limitar ou excluir nossa responsabilidade ou sua responsabilidade por mortes ou danos pessoais;<\/span><\/li><li><span style=\"color: #333333;\">limitar ou excluir nossa responsabilidade ou sua responsabilidade por fraudes ou deturpa\u00e7\u00f5es fraudulentas;<\/span><\/li><li><span style=\"color: #333333;\">limitar nossa responsabilidade ou sua responsabilidade de quaisquer maneiras que n\u00e3o forem permitidas sob a lei;<\/span><\/li><li><span style=\"color: #333333;\">excluir quaisquer responsabilidades suas ou nossas que n\u00e3o podem ser exclu\u00eddas de acordo com a lei aplic\u00e1vel.<\/span><\/li><\/ul><p><span style=\"color: #333333;\">As limita\u00e7\u00f5es e proibi\u00e7\u00f5es de responsabiliza\u00e7\u00e3o listadas nesta Se\u00e7\u00e3o e em outras partes desta declara\u00e7\u00e3o: (a) est\u00e3o sujeitas ao par\u00e1grafo anterior; e (b) regem todas as responsabiliza\u00e7\u00f5es que surgirem sob a declara\u00e7\u00e3o, incluindo responsabiliza\u00e7\u00f5es surgidas em contrato, em delitos e em quebra de obriga\u00e7\u00f5es legais.<\/span><\/p><p><span style=\"color: #333333;\">Enquanto o site e as informa\u00e7\u00f5es e servi\u00e7os do site forem oferecidos gratuitamente, n\u00f3s n\u00e3o seremos respons\u00e1veis por perdas e danos de qualquer natureza.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Termos e Condi\u00e7\u00f5es de Uso Seja bem-vindo ao O Guia Completo de Leil\u00f5es de Im\u00f3veis! Estes termos e condi\u00e7\u00f5es descrevem as regras de uso do site da empresa Guia Completo de Leil\u00f5es de Im\u00f3veis, localizado no endere\u00e7o https:\/\/oguiacompletodeleilaodeimoveis.thiagostolte.com.br\/. Ao acessar este site, consideramos que voc\u00ea est\u00e1 de acordo com os termos e condi\u00e7\u00f5es abaixo. N\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-461","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/thiagostolte.com.br\/oguiacompletodeleilaodeimoveis\/wp-json\/wp\/v2\/pages\/461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thiagostolte.com.br\/oguiacompletodeleilaodeimoveis\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thiagostolte.com.br\/oguiacompletodeleilaodeimoveis\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thiagostolte.com.br\/oguiacompletodeleilaodeimoveis\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thiagostolte.com.br\/oguiacompletodeleilaodeimoveis\/wp-json\/wp\/v2\/comments?post=461"}],"version-history":[{"count":16,"href":"https:\/\/thiagostolte.com.br\/oguiacompletodeleilaodeimoveis\/wp-json\/wp\/v2\/pages\/461\/revisions"}],"predecessor-version":[{"id":480,"href":"https:\/\/thiagostolte.com.br\/oguiacompletodeleilaodeimoveis\/wp-json\/wp\/v2\/pages\/461\/revisions\/480"}],"wp:attachment":[{"href":"https:\/\/thiagostolte.com.br\/oguiacompletodeleilaodeimoveis\/wp-json\/wp\/v2\/media?parent=461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}